{"id":317,"date":"2008-09-24T13:47:20","date_gmt":"2008-09-24T11:47:20","guid":{"rendered":"http:\/\/www.curi0us.net\/blog\/?p=317"},"modified":"2008-09-24T13:47:20","modified_gmt":"2008-09-24T11:47:20","slug":"demokratie-gez-und-das-zdf","status":"publish","type":"post","link":"https:\/\/www.curi0us.net\/blog\/2008\/09\/24\/demokratie-gez-und-das-zdf\/","title":{"rendered":"Demokratie, GEZ und das ZDF"},"content":{"rendered":"\n<!-- google_ad_section_start -->\n<p>Ich gebe ja offen zu, dass ich nur selten direkt auf politische Entscheidungen eingehe hier. Denke das wird auch so bleiben. Das bedeutet aber nicht, dass ich mich nicht f\u00fcr Politik interessiere. Heute hat mich das <a onclick=\"javascript:pageTracker._trackPageview('\/outgoing\/rz.koepke.net\/?p=901');\"  href=\"http:\/\/rz.koepke.net\/?p=901\" target=\"_blank\">Reizzentrum<\/a> auf ein gro\u00dfartiges Tool aufmerksam gemacht:<\/p>\n<p><a onclick=\"javascript:pageTracker._trackPageview('\/outgoing\/www.zdf.de\/ZDFmediathek\/content\/584336?inPopup=true');\"  href=\"http:\/\/www.zdf.de\/ZDFmediathek\/content\/584336?inPopup=true\" target=\"_blank\">Das Parlameter<\/a><\/p>\n<p>Das Parlameter erm\u00f6glicht es, sich das Abstimmungsverhalten der Bundestagsabgeordneten im Detail anzusehen. Dabei sind alle so genannten &#8222;<a onclick=\"javascript:pageTracker._trackPageview('\/outgoing\/de.wikipedia.org\/wiki\/Namentliche_Abstimmung#Namentliche_Abstimmungen');\"  href=\"http:\/\/de.wikipedia.org\/wiki\/Namentliche_Abstimmung#Namentliche_Abstimmungen\" target=\"_blank\">Namentlichen Abstimmungen<\/a>&#8220; ber\u00fccksichtigt.Wer hat daf\u00fcr, wer dagegen gestimmt, wer hat sich enthalten etc.. Finde ich ganz gro\u00dfartig. Das ist wirkliche Transparenz. Und da erf\u00fcllt das ZDF dann meiner Wahrnehmung nach auch mal wieder den Job den es eigentlich hat: Gute, unparteiische Informationen liefern. Dinge wie diese sind es, die dazu f\u00fchren, dass ich f\u00fcr ein Geb\u00fchrenfinanziertes Rundfunkprogramm bin. Und Dinge wie diese sind es auch, die zumindest ein wenig rechtfertigen k\u00f6nnen, dass die \u00d6ffentlich-Rechtlichen sich auch Online pr\u00e4sentieren.<\/p>\n<p>Ich habe immer noch enorm viel am bestehenden System auszusetzen. Aber man mu\u00df ja auch mal positives hervorheben \ud83d\ude42 In diesem Sinne: Danke ZDF f\u00fcr eine positive \u00dcberraschung.<\/p>\n\n<!-- google_ad_section_end -->\n","protected":false},"excerpt":{"rendered":"<p>Ich gebe ja offen zu, dass ich nur selten direkt auf politische Entscheidungen eingehe hier. Denke das wird auch so bleiben. Das bedeutet aber nicht, dass ich mich nicht f\u00fcr Politik interessiere. Heute hat mich das Reizzentrum auf ein gro\u00dfartiges &hellip; <a href=\"https:\/\/www.curi0us.net\/blog\/2008\/09\/24\/demokratie-gez-und-das-zdf\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,7],"tags":[54,363,364,640,33,362],"class_list":["post-317","post","type-post","status-publish","format-standard","hentry","category-kultur","category-politik","tag-gez","tag-parlament","tag-parlamenter","tag-politik","tag-tv","tag-zdf"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/posts\/317"}],"collection":[{"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/comments?post=317"}],"version-history":[{"count":1,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/posts\/317\/revisions"}],"predecessor-version":[{"id":318,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/posts\/317\/revisions\/318"}],"wp:attachment":[{"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/media?parent=317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/categories?post=317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/tags?post=317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}