{"id":298,"date":"2008-09-10T22:30:57","date_gmt":"2008-09-10T20:30:57","guid":{"rendered":"http:\/\/www.curi0us.net\/blog\/2008\/09\/10\/iphone-nicht-haben-wollen\/"},"modified":"2008-09-10T22:30:57","modified_gmt":"2008-09-10T20:30:57","slug":"iphone-nicht-haben-wollen","status":"publish","type":"post","link":"https:\/\/www.curi0us.net\/blog\/2008\/09\/10\/iphone-nicht-haben-wollen\/","title":{"rendered":"iPhone nicht haben wollen"},"content":{"rendered":"\n<!-- google_ad_section_start -->\n<p>Also ausnahmsweise mal nicht ich. Ich hab ja schon eins \ud83d\ude42 Aber einige Blogger die ich lese scheinen angefixed zu sein, von der Aktion die zur OMD gestartet wurde:   <br \/>Ein iPhone f\u00fcr den, der am 17. September um 22:00 beim Suchbegriff \u201cBefreiphone\u201d die Nummer eins ist. Bei Google:<\/p>\n<p>Henning von Hasenfarm schreibt \u2013 wie ich finde ganz zurecht \u2013 dass es viel spanneder gewesen w\u00e4re, wenn statt Google eine andere Suchmaschine gew\u00e4hlt worden w\u00e4re. Aber das Handy h\u00e4tte er wohl schon gerne. <a onclick=\"javascript:pageTracker._trackPageview('\/outgoing\/www.hasen-farm.de\/2008\/09\/10\/befreiphone-und-der-kampf-blogger-gegen-google\/');\"  href=\"http:\/\/www.hasen-farm.de\/2008\/09\/10\/befreiphone-und-der-kampf-blogger-gegen-google\/\" target=\"_blank\">Beifreiphone<\/a>. <\/p>\n<p><a onclick=\"javascript:pageTracker._trackPageview('\/outgoing\/www.eyesaiditbefore.de\/2008\/09\/10\/befreiphone\/');\"  href=\"http:\/\/www.eyesaiditbefore.de\/2008\/09\/10\/befreiphone\/\" target=\"_blank\">ESIB-Malcom<\/a> h\u00e4tte auch gern das Teledings, aber eigentlich eher f\u00fcr sein Projekt Supertopic. Auch hier: <a onclick=\"javascript:pageTracker._trackPageview('\/outgoing\/www.supertopic.de\/forum\/1\/befreiphone-7006-1.html');\"  href=\"http:\/\/www.supertopic.de\/forum\/1\/befreiphone-7006-1.html\" target=\"_blank\">Beifreiphone<\/a><\/p>\n<p>Und dann war da noch Udo vom Lawblog, auch er bat um einen Backlink (und da gibt\u2019s sogar was zu gewinnen\u2026) also hier: <a onclick=\"javascript:pageTracker._trackPageview('\/outgoing\/www.lawblog.de\/index.php\/archives\/2008\/09\/09\/befreiphone-haben-will\/');\"  href=\"http:\/\/www.lawblog.de\/index.php\/archives\/2008\/09\/09\/befreiphone-haben-will\/\" target=\"_blank\">Befreiphone<\/a><\/p>\n<p>Da ich allen drei Bloggern gewisse Sympathien entgegenbringe kann ich mich nicht entscheiden wer den Link bekommt, also einfach alle drei \ud83d\ude00 Viel Erfolg und im Zweifelsfall viel Spass mit dem kleinen Spielzeug! <\/p>\n<p>(Ja, dieses Posting ergibt sonst keinen weiteren Sinn!) <\/p>\n\n<!-- google_ad_section_end -->\n","protected":false},"excerpt":{"rendered":"<p>Also ausnahmsweise mal nicht ich. Ich hab ja schon eins \ud83d\ude42 Aber einige Blogger die ich lese scheinen angefixed zu sein, von der Aktion die zur OMD gestartet wurde: Ein iPhone f\u00fcr den, der am 17. September um 22:00 beim &hellip; <a href=\"https:\/\/www.curi0us.net\/blog\/2008\/09\/10\/iphone-nicht-haben-wollen\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,5],"tags":[354,186,211,284],"class_list":["post-298","post","type-post","status-publish","format-standard","hentry","category-it-und-technik","category-sinnloses","tag-backlinks","tag-blogging","tag-gewinnspiel","tag-iphone"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/posts\/298"}],"collection":[{"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/comments?post=298"}],"version-history":[{"count":0,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/posts\/298\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/media?parent=298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/categories?post=298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.curi0us.net\/blog\/wp-json\/wp\/v2\/tags?post=298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}